﻿{"id":221,"count":1,"description":"","link":"https:\/\/www.7pobles.com\/en\/category\/motxilles-de-guiatge\/","name":"motxilles de guiatge","slug":"motxilles-de-guiatge","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"jPHWcFIg-DtlAk8l95ZtHWHJwGuJP9RalcuE-RDv_3Y\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.7pobles.com\/en\/category\/motxilles-de-guiatge\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/221\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.7pobles.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/category\\\/motxilles-de-guiatge\\\/#listItem\",\"name\":\"motxilles de guiatge\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/category\\\/motxilles-de-guiatge\\\/#listItem\",\"position\":2,\"name\":\"motxilles de guiatge\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/221\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/221\\\/\",\"name\":\"motxilles de guiatge | 7pobles.com: Activitats de muntanya\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/221\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/#organization\",\"name\":\"7pobles.com\",\"description\":\"Guiatges, cursos, formaci\\u00f3 i educaci\\u00f3 ambiental\",\"url\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/\",\"email\":\"info@7pobles.com\",\"telephone\":\"+34615306447\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.7pobles.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo_quadrat_7pobles_joel-300x300color.jpg\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/221\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/221\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/7pobles\\\/\",\"https:\\\/\\\/instagram.com\\\/7pobles\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/\",\"name\":\"7pobles.com: Vine a descobrir la Tinen\\u00e7a\",\"description\":\"Guiatges, cursos, formaci\\u00f3 i educaci\\u00f3 ambiental\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.7pobles.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"motxilles de guiatge | 7pobles.com: Activitats de muntanya","description":"","canonical_url":"https:\/\/www.7pobles.com\/en\/category\/motxilles-de-guiatge\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"jPHWcFIg-DtlAk8l95ZtHWHJwGuJP9RalcuE-RDv_3Y","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.7pobles.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.7pobles.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.7pobles.com\/en\/category\/motxilles-de-guiatge\/#listItem","name":"motxilles de guiatge"}},{"@type":"ListItem","@id":"https:\/\/www.7pobles.com\/en\/category\/motxilles-de-guiatge\/#listItem","position":2,"name":"motxilles de guiatge","previousItem":{"@type":"ListItem","@id":"https:\/\/www.7pobles.com\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221\/#collectionpage","url":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221\/","name":"motxilles de guiatge | 7pobles.com: Activitats de muntanya","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.7pobles.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.7pobles.com\/en\/#organization","name":"7pobles.com","description":"Guiatges, cursos, formaci\u00f3 i educaci\u00f3 ambiental","url":"https:\/\/www.7pobles.com\/en\/","email":"info@7pobles.com","telephone":"+34615306447","logo":{"@type":"ImageObject","url":"https:\/\/www.7pobles.com\/wp-content\/uploads\/2018\/10\/logo_quadrat_7pobles_joel-300x300color.jpg","@id":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221\/#organizationLogo"},"image":{"@id":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/7pobles\/","https:\/\/instagram.com\/7pobles"]},{"@type":"WebSite","@id":"https:\/\/www.7pobles.com\/en\/#website","url":"https:\/\/www.7pobles.com\/en\/","name":"7pobles.com: Vine a descobrir la Tinen\u00e7a","description":"Guiatges, cursos, formaci\u00f3 i educaci\u00f3 ambiental","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.7pobles.com\/en\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.7pobles.com\/en\/wp-json\/wp\/v2\/posts?categories=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}